{"id":38934,"date":"2015-09-29T11:28:08","date_gmt":"2015-09-29T09:28:08","guid":{"rendered":"https:\/\/www.procamera-app.com\/?p=38934"},"modified":"2023-04-06T15:35:10","modified_gmt":"2023-04-06T13:35:10","slug":"procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus","status":"publish","type":"post","link":"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/","title":{"rendered":"ProCamera&#8217;s iPhone Fotovergleich: 6, 6 S, 6 Plus, 6 S Plus"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Wir hier bei ProCamera befassen\u00a0uns 7 Tage die Woche mit der iPhone Kamera. Ihr k\u00f6nnt euch also vorstellen, wie sehr wir den neuen Ger\u00e4ten entgegenfiebern. Gestern kam\u00a0die Benachrichtigung, dass unsere Lieferung wohl direkt zum heutigen Verkaufsstart bei uns eintreffen wird. In diesem Blogpost wollen wir \u00fcber den Tag hinweg unsere ersten Eindr\u00fccke zu den neuen Ger\u00e4ten mit euch teilen. Da wir den Beitrag stufenweise ausbauen, lohnt es sich immer wieder vorbeizuschauen.<\/p>\n<p style=\"text-align: center;\"><strong>Jetzt hei\u00dft es iPhone 6 vs 6 S vs 6 Plus vs 6 S Plus<\/strong>.<\/p>\n<p>[\/vc_column_text]<div class=\"ult-spacer spacer-6a97743343d39\" data-id=\"6a97743343d39\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div><div class=\"hr-thin style-line\" style=\"width: 100%;border-top-width: 1px;\"><\/div><div class=\"ult-spacer spacer-6a97743343d93\" data-id=\"6a97743343d93\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/4&#8243;][vc_single_image image=&#8220;42458&#8243; img_size=&#8220;&#8220; css_animation=&#8220;fadeIn&#8220;]<div class=\"ult-spacer spacer-6a97743343da9\" data-id=\"6a97743343da9\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][vc_column width=&#8220;3\/4&#8243;][vc_column_text]<em><strong>11:38 UHR<br \/>\n<\/strong><\/em>Noch keine Spur vom Postkurier&#8230; Zur Erkl\u00e4rung, was wir heute geplant haben: Sobald die Lieferung bei uns eintrifft, werden wir die 4 neuesten Ger\u00e4te miteinander vergleichen k\u00f6nnen \u2013 iPhone 6, 6 S, 6 Plus und 6 S Plus. Mit allen\u00a0vier Ger\u00e4ten wollen wir dann losziehen, um erste Vergleichsfotos zu schie\u00dfen.<br \/>\nAlle Aufnahmen werden erstellt mit ProCamera v9.0. Dank des manuellen Modus in ProCamera k\u00f6nnen wir sicherstellen, dass alle Fotos mit den gleichen Kameraeinstellungen gemacht werden: <strong>Belichtungszeit, ISO-Empfindlichkeit, Fokusposition und Wei\u00dfabgleich<\/strong>. Unsere Fototour soll kein Labortest werden, der\u00a0sich\u00a0mit wissenschaftlichen Farbpaletten und einer Menge feiner Linien besch\u00e4ftigt\u00a0\u2013 stattdessen m\u00f6chten wir lebensnahe Aufnahmesituationen nachstellen und untersuchen, inwieweit wir Unterschiede feststellen k\u00f6nnen. Um den &#8222;menschlichen Faktor&#8220; soweit wie m\u00f6glich zu minimieren, werden die Smartphones jeweils auf ein <strong>Stativ<\/strong> montiert.<br \/>\nDar\u00fcber hinaus werden die Dateien im verlustfreien TIFF-Format abgespeichert. Klicken auf eines der nachfolgenden Bilder \u00f6ffnet jeweils eine gr\u00f6\u00dfere Ansicht.[\/vc_column_text]<div class=\"ult-spacer spacer-6a97743343dc3\" data-id=\"6a97743343dc3\" data-height=\"40\" data-height-mobile=\"40\" data-height-tab=\"40\" data-height-tab-portrait=\"40\" data-height-mobile-landscape=\"40\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/4&#8243;][vc_column_text]<em><strong>12:06\u00a0UHR<br \/>\n<\/strong><\/em>Es klingelt an der T\u00fcr. Es ist der Postkurier! Wir wissen, was in diesen Paketen ist!!<br \/>\nJetzt nehmen\u00a0wir die neuen Ger\u00e4te so schnell wie m\u00f6glich in Betrieb, und dann geht es ab nach drau\u00dfen mit ihnen.[\/vc_column_text]<div class=\"ult-spacer spacer-6a97743343dd5\" data-id=\"6a97743343dd5\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][vc_column width=&#8220;3\/4&#8243;][vc_single_image image=&#8220;42671&#8243; img_size=&#8220;full&#8220; onclick=&#8220;link_image&#8220; css_animation=&#8220;fadeIn&#8220;]<div class=\"ult-spacer spacer-6a97743343de6\" data-id=\"6a97743343de6\" data-height=\"40\" data-height-mobile=\"40\" data-height-tab=\"40\" data-height-tab-portrait=\"40\" data-height-mobile-landscape=\"40\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"hr-thin style-line\" style=\"width: 100%;border-top-width: 1px;\"><\/div><div class=\"ult-spacer spacer-6a97743343e08\" data-id=\"6a97743343e08\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<em><strong>14:48\u00a0UHR<br \/>\n<\/strong><\/em>Hier haben wir einen ersten Foto-Vergleich f\u00fcr euch. Aufnahmen der vier Ger\u00e4te nebeneinander plus Ausschnittsvergr\u00f6\u00dferungen. Durch den Sprung in der Aufl\u00f6sung (von den bisherigen 8 auf 12 Megapixel) unterscheidet sich der 100% Ausschnitt der neuesten Ger\u00e4ten von denen der vorherigen Generation.<br \/>\nDa dies skalierte Jpeg-Dateien sind, teilen\u00a0wir auch unsere Originalfotos im TIFF-Format mit euch:\u00a0<a href=\"https:\/\/www.dropbox.com\/sh\/6pvhniavszfhxhr\/AAA9NIBUElcila-k_UaZvcz6a?dl=0\" target=\"_blank\" rel=\"noopener\">Vergleichsfoto Archiv (verlustfreie TIFF-Dateien)<\/a><br \/>\nJetzt gehen wir noch einmal los f\u00fcr weitere Aufnahmen. Bis sp\u00e4ter&#8230;[\/vc_column_text]<div class=\"ult-spacer spacer-6a97743343e18\" data-id=\"6a97743343e18\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[vc_single_image image=&#8220;42677&#8243; img_size=&#8220;full&#8220; onclick=&#8220;custom_link&#8220; img_link_target=&#8220;_blank&#8220; link=&#8220;https:\/\/www.procamera-app.com\/wp-content\/uploads\/2015\/09\/Testphoto1_iPhone6-6S-6Plus-6SPlus_Collage_1722x10241.jpg&#8220;]<div class=\"ult-spacer spacer-6a97743343e29\" data-id=\"6a97743343e29\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<em><strong>18:21\u00a0UHR<br \/>\n<\/strong><\/em>Die Zeit verging wie im Flug mit den neuen Ger\u00e4ten. Auff\u00e4llig ist wie immer die \u00fcberragende Verarbeitungsqualit\u00e4t \u2013 man merkt sofort, dass man ein wertiges Ger\u00e4t in den H\u00e4nden h\u00e4lt. Interessant wirkt das neue 3D Touch, mal sehen, was unseren Programmierern dazu einf\u00e4llt&#8230;<br \/>\nBeim genauen Betrachten unserer ersten Testaufnahmen l\u00e4sst sich festhalten, dass es in der Tat Unterschiede gibt; aber\u00a0einen\u00a0Quantensprung stellt es nicht dar. Man muss ber\u00fccksichtigen, dass bereits im iPhone 6 und 6 Plus exzellente Kameras verbaut sind.<br \/>\nNat\u00fcrlich wollen wir unser finales Urteil nicht anhand einer Handvoll Aufnahmen vom\u00a0ersten Tag f\u00e4llen. Daher werden wir in den n\u00e4chsten Tagen und Wochen weiterhin parallel Fotos aufnehmen und untersuchen.<br \/>\nWir freuen uns selbstverst\u00e4ndlich, wenn ihr uns eure pers\u00f6nlichen Eindr\u00fccke im Kommentarfeld weiter unten schildert.<\/p>\n<p>Hier nun noch ein weiteres Vergleichsfoto unseres heutigen Photowalks. Bei den Ausschnittsvergr\u00f6\u00dferungen sieht man mehr Details auf\u00a0den Fotos der neuesten iPhones. Um die Unterschiede deutlicher zu zeigen, wurden die Ausschnitte auf weit mehr als 100% vergr\u00f6\u00dfert. Gerade wenn man Bildausschnitte (beispielsweise\u00a0f\u00fcr den Druck) vergr\u00f6\u00dfern m\u00f6chte oder die eigenen Fotos nach der Aufnahme gern noch einmal zuschneidet, ist die h\u00f6here Pixelanzahl eine wertvolle Reserve.<\/p>\n<p>Auch im Umgang mit Farbe konnten wir\u00a0Unterschiede feststellen. Wir nutzten ProCameras manuellen Wei\u00dfabgleich, um zu testen, ob wir im Hinblick auf Farbigkeit bei gleichen Werten nahezu identische Resultate erhalten. Die Ergebnisse unterschieden sich jedoch merklich, was man gut am Stra\u00dfenschild im nachfolgenden\u00a0Foto erkennt. Bei automatischem Wei\u00dfabgleich werden die Unterschiede zwischen den Ger\u00e4tegenerationen schon deutlich geringer. Weiter relativiert sich der Unterschied bei der Ansicht der unterschiedlichen Fotos auf einem Ger\u00e4t, da auch die Bildschirme zur leicht unterschiedlichen Farbwiedergabe beitragen.[\/vc_column_text]<div class=\"ult-spacer spacer-6a97743343e37\" data-id=\"6a97743343e37\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[vc_single_image image=&#8220;42681&#8243; img_size=&#8220;full&#8220; onclick=&#8220;custom_link&#8220; img_link_target=&#8220;_blank&#8220; link=&#8220;https:\/\/www.procamera-app.com\/wp-content\/uploads\/2015\/09\/Testphoto2_iPhone6-6S-6Plus-6SPlus_Collage_1722x10801.jpg&#8220;]<div class=\"ult-spacer spacer-6a97743343e46\" data-id=\"6a97743343e46\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<em><strong>19:38\u00a0UHR<br \/>\n<\/strong><\/em>Nun m\u00fcssen wir uns bereits von zweien\u00a0unserer neuen Ger\u00e4te verabschieden. Diese senden wir zu unserem Technologiepartner Ittiam Systems in Indien, wo sie sehr genau analysiert werden. Die dabei entstehenden Kamera Profile (Camera Response Curve) erm\u00f6glichen es uns, auch auf den neuesten Ger\u00e4ten die beste HDR-Verarbeitung anzubieten. Da jede Ger\u00e4tegeneration diesbez\u00fcglich eine eigene Charakteristik aufweist, wird die vividHDR Technologie immer wieder speziell daf\u00fcr optimiert. So k\u00f6nnen wir die sehr hohe Qualit\u00e4t auf allen unterst\u00fctzten Ger\u00e4ten gew\u00e4hrleisten.<br \/>\nFalls du bereits jetzt schon eines der neuen iPhones besitzt, bitten wir um ein klein wenig Geduld. Wir werden schnellstm\u00f6glich die HDR-Optimierungen f\u00fcr iPhone 6 S und 6 S Plus\u00a0\u00fcber ein kostenloses Update implementieren.[\/vc_column_text]<div class=\"ult-spacer spacer-6a97743343e54\" data-id=\"6a97743343e54\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[vc_single_image image=&#8220;42683&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220; onclick=&#8220;link_image&#8220;]<div class=\"ult-spacer spacer-6a97743343e63\" data-id=\"6a97743343e63\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<em><strong>20:02\u00a0UHR<br \/>\n<\/strong><\/em>Der Tag neigt sich\u00a0dem Ende\u00a0zu. Es war spannend, alle vier Ger\u00e4te Seite an Seite zu testen, um einen ersten pers\u00f6nlichen Eindruck zu bekommen. Wir werden mit Sicherheit auch am Wochenende nicht die H\u00e4nde von den neuen Ger\u00e4ten lassen k\u00f6nnen und noch Weiteres ausprobieren. Vielen Dank an diejenigen, die uns hier im Blog in \u00a0den letzten Stunden\u00a0begleitet haben.<br \/>\nF\u00fcr alle, die (noch) kein neues Ger\u00e4t besitzen: Keine Sorge, es ist der Mensch hinter der Kamera, der verantwortlich f\u00fcr\u00a0unvergessliche Aufnahmen ist. Mit ein wenig fotografischem Grundwissen, einer kreativen Sichtweise und ProCamera besitzt du bereits alles, was n\u00f6tig ist.\u00a0Genie\u00dft das Wochenende und nutzt\u00a0das sch\u00f6ne Herbstlicht \u2013 und falls es doch regnen sollte,\u00a0steht unsere aktualisierte <a href=\"http:\/\/procamera-app.com\/procamera_manual\/ProCamera_Manual_DE.pdf\" target=\"_blank\" rel=\"noopener\">Bedienungsanleitung zum Download bereit<\/a>.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"ult-spacer spacer-6a97743343e72\" data-id=\"6a97743343e72\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div><div class=\"hr-thin style-line\" style=\"width: 100%;border-top-width: 1px;\"><\/div><div class=\"ult-spacer spacer-6a97743343e8d\" data-id=\"6a97743343e8d\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<em><strong>FORTSETZUNG<br \/>\n<\/strong><\/em>Wie zu erwarten war, konnten wir auch am Wochenende die neuen Ger\u00e4te nicht aus der Hand legen. Das folgende Foto ist am Sonntag entstanden, indem parallel mit einem iPhone 6 und einem iPhone 6 S fotografiert wurde. Die Vergr\u00f6\u00dferung der Turmspitze zeigt, dass die feinen Strukturen mit dem iPhone 6 S besser dargestellt werden k\u00f6nnen. Per Klick auf das Foto kann eine gr\u00f6\u00dfere Ansicht ge\u00f6ffnet werden, mit der man die Unterschiede noch besser erkennen und bewerten kann.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"ult-spacer spacer-6a97743343e9b\" data-id=\"6a97743343e9b\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[vc_single_image image=&#8220;42691&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220; onclick=&#8220;custom_link&#8220; link=&#8220;https:\/\/www.procamera-app.com\/wp-content\/uploads\/2015\/10\/Testfoto3_i6_i6S_Tag2.jpg&#8220;]<div class=\"ult-spacer spacer-6a97743343ea9\" data-id=\"6a97743343ea9\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]Auch beim zweiten Foto hat das iPhone 6 S etwas die Nase vorne. In der Ausschnittsvergr\u00f6\u00dferung ist die\u00a0noch einmal leicht gesteigerte\u00a0Sch\u00e4rfe und die h\u00f6here Aufl\u00f6sung des iPhone 6 S erkennbar.[\/vc_column_text]<div class=\"ult-spacer spacer-6a97743343eb6\" data-id=\"6a97743343eb6\" data-height=\"25\" data-height-mobile=\"25\" data-height-tab=\"25\" data-height-tab-portrait=\"25\" data-height-mobile-landscape=\"25\" style=\"clear:both;display:block;\"><\/div>[vc_single_image image=&#8220;42695&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220; onclick=&#8220;custom_link&#8220; link=&#8220;https:\/\/www.procamera-app.com\/wp-content\/uploads\/2015\/10\/Testfoto4_i6_i6S_Tag2.jpg&#8220;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Wir hier bei ProCamera setzen uns 7 Tage die Woche mit der iPhone Kamera auseinander. Daher kann man sich vorstellen, wie sehr wir den neuen Ger\u00e4ten entgegenfiebern. Gestern erhielten wir die Benachrichtigung, dass unsere Lieferung wohl direkt zum heutigen Verkaufsstart bei uns eintreffen wird. In diesem Blogpost wollen wir \u00fcber den Tag hinweg unsere ersten Eindr\u00fccke zu den neuen Ger\u00e4ten mit euch teilen.<\/p>\n","protected":false},"author":15,"featured_media":42673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[288,345],"tags":[982,983,1529,1594,985,1767,1316,984],"class_list":["post-38934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-how-to-de","category-whats-new-de","tag-6-s","tag-6-s-plus","tag-iphone-de","tag-unterwasserkamera","tag-kameratest","tag-objektiv-de","tag-procamera-de-2","tag-vergleich","category-288","category-345","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ProCamera&#039;s iPhone Fotovergleich: 6, 6 S, 6 Plus, 6 S Plus - ProCamera Blog - Turn your iPhone into a powerful digital camera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ProCamera&#039;s iPhone Fotovergleich: 6, 6 S, 6 Plus, 6 S Plus - ProCamera Blog - Turn your iPhone into a powerful digital camera\" \/>\n<meta property=\"og:description\" content=\"Wir hier bei ProCamera setzen uns 7 Tage die Woche mit der iPhone Kamera auseinander. Daher kann man sich vorstellen, wie sehr wir den neuen Ger\u00e4ten entgegenfiebern. Gestern erhielten wir die Benachrichtigung, dass unsere Lieferung wohl direkt zum heutigen Verkaufsstart bei uns eintreffen wird. In diesem Blogpost wollen wir \u00fcber den Tag hinweg unsere ersten Eindr\u00fccke zu den neuen Ger\u00e4ten mit euch teilen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/\" \/>\n<meta property=\"og:site_name\" content=\"ProCamera Blog - Turn your iPhone into a powerful digital camera\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ProCameraApp\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-29T09:28:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-06T13:35:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.procamera-app.com\/wp-content\/uploads\/2015\/09\/Unboxing_Square_FeaturedImage.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Team ProCamera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProCamera\" \/>\n<meta name=\"twitter:site\" content=\"@ProCamera\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Team ProCamera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/\",\"url\":\"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/\",\"name\":\"ProCamera's iPhone Fotovergleich: 6, 6 S, 6 Plus, 6 S Plus - ProCamera Blog - Turn your iPhone into a powerful digital camera\",\"isPartOf\":{\"@id\":\"https:\/\/procamera-app.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.procamera-app.com\/wp-content\/uploads\/2015\/09\/Unboxing_Square_FeaturedImage.jpg\",\"datePublished\":\"2015-09-29T09:28:08+00:00\",\"dateModified\":\"2023-04-06T13:35:10+00:00\",\"author\":{\"@id\":\"https:\/\/procamera-app.com\/en\/#\/schema\/person\/f5fd497c3870f674eedc2ad21b095a88\"},\"breadcrumb\":{\"@id\":\"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/#primaryimage\",\"url\":\"https:\/\/www.procamera-app.com\/wp-content\/uploads\/2015\/09\/Unboxing_Square_FeaturedImage.jpg\",\"contentUrl\":\"https:\/\/www.procamera-app.com\/wp-content\/uploads\/2015\/09\/Unboxing_Square_FeaturedImage.jpg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/procamera-app.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ProCamera&#8217;s iPhone Fotovergleich: 6, 6 S, 6 Plus, 6 S Plus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/procamera-app.com\/en\/#website\",\"url\":\"https:\/\/procamera-app.com\/en\/\",\"name\":\"ProCamera Blog - Turn your iPhone into a powerful digital camera\",\"description\":\"ProCamera ist die iOS-App f\u00fcr Fotografie, Video und Foto-Nachbearbeitung auf Profi-Niveau!\\r\\n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/procamera-app.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/procamera-app.com\/en\/#\/schema\/person\/f5fd497c3870f674eedc2ad21b095a88\",\"name\":\"Team ProCamera\",\"url\":\"https:\/\/procamera-app.com\/de\/blog\/author\/procamera\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ProCamera's iPhone Fotovergleich: 6, 6 S, 6 Plus, 6 S Plus - ProCamera Blog - Turn your iPhone into a powerful digital camera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/","og_locale":"de_DE","og_type":"article","og_title":"ProCamera's iPhone Fotovergleich: 6, 6 S, 6 Plus, 6 S Plus - ProCamera Blog - Turn your iPhone into a powerful digital camera","og_description":"Wir hier bei ProCamera setzen uns 7 Tage die Woche mit der iPhone Kamera auseinander. Daher kann man sich vorstellen, wie sehr wir den neuen Ger\u00e4ten entgegenfiebern. Gestern erhielten wir die Benachrichtigung, dass unsere Lieferung wohl direkt zum heutigen Verkaufsstart bei uns eintreffen wird. In diesem Blogpost wollen wir \u00fcber den Tag hinweg unsere ersten Eindr\u00fccke zu den neuen Ger\u00e4ten mit euch teilen.","og_url":"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/","og_site_name":"ProCamera Blog - Turn your iPhone into a powerful digital camera","article_publisher":"https:\/\/www.facebook.com\/ProCameraApp","article_published_time":"2015-09-29T09:28:08+00:00","article_modified_time":"2023-04-06T13:35:10+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/www.procamera-app.com\/wp-content\/uploads\/2015\/09\/Unboxing_Square_FeaturedImage.jpg","type":"image\/jpeg"}],"author":"Team ProCamera","twitter_card":"summary_large_image","twitter_creator":"@ProCamera","twitter_site":"@ProCamera","twitter_misc":{"Verfasst von":"Team ProCamera","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/","url":"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/","name":"ProCamera's iPhone Fotovergleich: 6, 6 S, 6 Plus, 6 S Plus - ProCamera Blog - Turn your iPhone into a powerful digital camera","isPartOf":{"@id":"https:\/\/procamera-app.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/#primaryimage"},"image":{"@id":"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procamera-app.com\/wp-content\/uploads\/2015\/09\/Unboxing_Square_FeaturedImage.jpg","datePublished":"2015-09-29T09:28:08+00:00","dateModified":"2023-04-06T13:35:10+00:00","author":{"@id":"https:\/\/procamera-app.com\/en\/#\/schema\/person\/f5fd497c3870f674eedc2ad21b095a88"},"breadcrumb":{"@id":"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/#primaryimage","url":"https:\/\/www.procamera-app.com\/wp-content\/uploads\/2015\/09\/Unboxing_Square_FeaturedImage.jpg","contentUrl":"https:\/\/www.procamera-app.com\/wp-content\/uploads\/2015\/09\/Unboxing_Square_FeaturedImage.jpg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/procamera-app.com\/de\/blog\/procameras-iphone-camera-comparison-6-6-s-6-plus-6-s-plus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/procamera-app.com\/de\/"},{"@type":"ListItem","position":2,"name":"ProCamera&#8217;s iPhone Fotovergleich: 6, 6 S, 6 Plus, 6 S Plus"}]},{"@type":"WebSite","@id":"https:\/\/procamera-app.com\/en\/#website","url":"https:\/\/procamera-app.com\/en\/","name":"ProCamera Blog - Turn your iPhone into a powerful digital camera","description":"ProCamera ist die iOS-App f\u00fcr Fotografie, Video und Foto-Nachbearbeitung auf Profi-Niveau!\r\n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/procamera-app.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/procamera-app.com\/en\/#\/schema\/person\/f5fd497c3870f674eedc2ad21b095a88","name":"Team ProCamera","url":"https:\/\/procamera-app.com\/de\/blog\/author\/procamera\/"}]}},"_links":{"self":[{"href":"https:\/\/procamera-app.com\/de\/wp-json\/wp\/v2\/posts\/38934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/procamera-app.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/procamera-app.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/procamera-app.com\/de\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/procamera-app.com\/de\/wp-json\/wp\/v2\/comments?post=38934"}],"version-history":[{"count":2,"href":"https:\/\/procamera-app.com\/de\/wp-json\/wp\/v2\/posts\/38934\/revisions"}],"predecessor-version":[{"id":61277,"href":"https:\/\/procamera-app.com\/de\/wp-json\/wp\/v2\/posts\/38934\/revisions\/61277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/procamera-app.com\/de\/wp-json\/wp\/v2\/media\/42673"}],"wp:attachment":[{"href":"https:\/\/procamera-app.com\/de\/wp-json\/wp\/v2\/media?parent=38934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/procamera-app.com\/de\/wp-json\/wp\/v2\/categories?post=38934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/procamera-app.com\/de\/wp-json\/wp\/v2\/tags?post=38934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}